{"id":49610,"date":"2026-07-30T11:22:49","date_gmt":"2026-07-30T15:22:49","guid":{"rendered":"https:\/\/foodbankscanada.ca\/?page_id=49610"},"modified":"2026-07-30T11:30:15","modified_gmt":"2026-07-30T15:30:15","slug":"foire-aux-questions","status":"publish","type":"page","link":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/","title":{"rendered":"Foire aux questions"},"content":{"rendered":"<section class=\" block block-image-text-button-list image-text-button-list  aligndefault\"\n         style=\"  background-color: rgba(254, 245, 221, 0); \">\n  <div class=\"container-lg px-0 d-flex flex-column flex-lg-row-reverse\">\n    \n    <div class=\"container-lg px-0 px-lg-2 col-12 col-lg-8\">\n      \n      <div class=\"slider-padding-div mb-4\">\n        <div\n          class=\"image-text-button-swiper swiper\"\n          style=\"--swiper-theme-color: #FFBE00; width: 100%;\"\n          data-autoscroll=\"false\"\n          data-delay=\"3000\"\n        >\n          <div class=\"swiper-wrapper\">\n                           \n                <div\n                  class=\"swiper-slide image-banner\"\n                  style=\"background-size: cover; background-position: center; background-repeat: no-repeat;\n                                        aspect-ratio: 1.9166666666667;\n                                              background-image: url('https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg');\n                                                              width: 100%;\"\n                  role=\"img\"\n                  aria-label=\"\"\n                ><\/div>\n                                    <\/div>\n\n                  <\/div>\n      <\/div>\n\n      \n              <div class=\"d-none d-lg-block\">\n          \n        <\/div>\n          <\/div>\n\n    \n    <div class=\"container col-12 col-lg-4 text-break\">\n      <div class=\"breadcrumbs-section    \n   breadcrumbs_normal \">\n  <p id=\"breadcrumbs\" class=\"\"><span><span><a href=\"https:\/\/foodbankscanada.ca\/fr\/\">Accueil<\/a><\/span><\/span><\/p><\/div>              <div class=\"mt-4\">\n          <h1>Foire aux questions<\/h1>\n<p>Vous avez des questions sur les dons \u00e0 Banques alimentaires Canada? Trouvez des r\u00e9ponses aux questions les plus fr\u00e9quentes concernant les dons, les re\u00e7us fiscaux, les dons mensuels et l\u2019impact de votre soutien aupr\u00e8s des personnes en situation d\u2019ins\u00e9curit\u00e9 alimentaire partout au Canada.<\/p>\n\n        <\/div>\n      \n              <div class=\"mt-4 d-block d-lg-none\">\n          \n        <\/div>\n          <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-a-quoi-sert-mon-don-a-banques-alimentaires-canada\">\u00c0 quoi sert mon don \u00e0 Banques alimentaires Canada?<\/h4>\n\n\n\n<p>Votre soutien procure un soulagement essentiel aux banques alimentaires et aux familles en soulageant la faim aujourd\u2019hui et en pr\u00e9venant la faim demain.<\/p>\n\n\n\n<p>Voici comment votre don nous aide&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Obtenir en denr\u00e9es nutritives au meilleur prix possible et \u00e0 les acheminer rapidement aux banques alimentaires partenaires partout au pays. L\u2019objectif est de remplir leurs tablettes pour r\u00e9pondre \u00e0 la demande qui monte en fl\u00e8che.<\/li>\n\n\n\n<li>Fournir aux banques alimentaires les outils dont elles ont besoin pour r\u00e9pondre aux besoins grandissants,&nbsp; qu\u2019il s\u2019agisse de cong\u00e9lateurs, de camions r\u00e9frig\u00e9r\u00e9s ou d\u2019entrep\u00f4ts plus grands, afin qu\u2019elles puissent mieux servir leur communaut\u00e9.<\/li>\n\n\n\n<li>Apporter des changements r\u00e9els et durables et \u00e0 plaider pour des politiques \u00e0 long terme visant \u00e0 surmonter les causes profondes de la faim.<\/li>\n<\/ul>\n\n\n\n<p><br><br><a href=\"https:\/\/foodbankscanada.ca\/fr\/give\/.\"><strong>Pour en savoir plus<\/strong><\/a><\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-comment-puis-je-obtenir-une-copie-de-mon-recu-fiscal\">Comment puis-je obtenir une copie de mon re\u00e7u fiscal?<\/h4>\n\n\n\n<p>Pour les dons en ligne, vous pouvez trouver une copie de votre re\u00e7u fiscal dans votre <strong><a href=\"https:\/\/support.foodbankscanada.ca\/login\">portail des donateurs<\/a>.<\/strong><\/p>\n\n\n\n<p>Les dons ponctuels donnent automatiquement lieu \u00e0 l\u2019\u00e9mission d\u2019un re\u00e7u au moment du traitement, tandis que les dons mensuels font l\u2019objet d\u2019un re\u00e7u annuel.<\/p>\n\n\n\n<p>Pour toute question concernant les re\u00e7us, \u00e9crivez-nous \u00e0 l\u2019adresse <a href=\"mailto:giving@foodbankscanada.ca\"><strong>giving@foodbankscanada.ca<\/strong><\/a> ou appelez-nous au <strong>905-602-5234, poste&nbsp;888.<\/strong><\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-comment-puis-je-mettre-a-jour-mon-don-mensuel\">Comment puis-je mettre \u00e0 jour mon don mensuel?<\/h4>\n\n\n\n<p>Pour mettre \u00e0 jour votre don mensuel, connectez-vous au <a href=\"https:\/\/support.foodbankscanada.ca\/login\"><strong>portail des donateurs.<\/strong><\/a><\/p>\n\n\n\n<p>Si vous avez besoin d\u2019aide suppl\u00e9mentaire, \u00e9crivez-nous \u00e0 l\u2019adresse <a href=\"mailto:giving@foodbankscanada.ca\"><strong>giving@foodbankscanada.ca<\/strong><\/a> ou appelez-nous au <strong>905-602-5234, poste&nbsp; 888<\/strong><\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-quelle-est-la-difference-entre-les-dons-a-banques-alimentaires-canada-et-ceux-a-ma-banque-alimentaire-locale\">Quelle est la diff\u00e9rence entre les dons \u00e0 Banques alimentaires Canada et ceux \u00e0 ma banque alimentaire locale?<\/h4>\n\n\n\n<p>Le soutien de votre banque alimentaire locale est un moyen important de changer la donne dans votre communaut\u00e9. Banques alimentaires Canada soutient \u00e9galement votre banque alimentaire locale, ainsi que plus de 5&nbsp;500&nbsp;banques alimentaires et organismes communautaires partout au pays.<\/p>\n\n\n\n<p>Comme vous pouvez l\u2019imaginer, l\u2019approvisionnement de suffisamment de nourriture constitue un d\u00e9fi de taille. Les banques alimentaires locales comptent donc sur notre aide. En tant qu\u2019organisme national, Banques alimentaires Canada est particuli\u00e8rement bien plac\u00e9 pour obtenir et distribuer des dons \u00e0 grande \u00e9chelle d\u2019aliments de qualit\u00e9 partout au pays, en fonction des besoins locaux.<\/p>\n\n\n\n<p>Nous fournissons \u00e9galement du financement, des services et des ressources pour aider les banques alimentaires \u00e0 fonctionner plus efficacement et \u00e0 servir un plus grand nombre de personnes dans le besoin,&nbsp; par exemple avec la formation sur la manipulation s\u00e9curitaire des aliments, l\u2019infrastructure de r\u00e9frig\u00e9ration et le soutien aux solutions communautaires de lutte contre la faim dans des endroits mal desservis comme le Nord.<\/p>\n\n\n\n<p>Notre travail va au-del\u00e0 de la lutte contre la faim aujourd\u2019hui.&nbsp; Banques alimentaires Canada dirige les efforts collectifs visant \u00e0 faire progresser les changements de politiques gouvernementales n\u00e9cessaires pour r\u00e9duire l\u2019ins\u00e9curit\u00e9 alimentaire.&nbsp;<\/p>\n\n\n\n<p>En soutenant Banques alimentaires Canada, vous renforcez les banques alimentaires et les organismes communautaires d\u2019un oc\u00e9an \u00e0 l\u2019autre, tout en contribuant \u00e0 stimuler le changement pour un avenir au Canada o\u00f9 personne ne souffre de la faim.<\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-puis-je-designer-mon-don-a-une-banque-alimentaire-en-particulier\">Puis-je d\u00e9signer mon don \u00e0 une banque alimentaire en particulier? <\/h4>\n\n\n\n<p>Les dons vers\u00e9s \u00e0 Banques alimentaires Canada appuient des programmes nationaux qui aident les banques alimentaires partout au pays, et non une banque alimentaire en particulier.<\/p>\n\n\n\n<p>Si vous souhaitez soutenir votre banque alimentaire locale, utilisez l\u2019outil <strong><a href=\"https:\/\/foodbankscanada.ca\/fr\/trouver-une-banque-alimentaire\/\">Trouver une banque alimentaire<\/a><\/strong> pour trouver votre banque alimentaire locale.&nbsp;&nbsp;<\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-j-ai-de-la-nourriture-a-donner-avec-qui-dois-je-communiquer\">J\u2019ai de la nourriture \u00e0 donner. Avec qui dois-je communiquer?<\/h4>\n\n\n\n<p>Merci pour votre don! Pour les petits articles de garde-manger, nous vous recommandons de faire ce don \u00e0 votre banque alimentaire locale. Utilisez notre outil <a href=\"https:\/\/foodbankscanada.ca\/fr\/trouver-une-banque-alimentaire\/\"><strong>Trouver une banque alimentaire<\/strong><\/a> pour en trouver une dans votre communaut\u00e9.&nbsp;<\/p>\n\n\n\n<p>Pour les dons \u00e0 grande \u00e9chelle (comme les dons d\u2019entreprise ou d\u2019agriculture), communiquez avec notre \u00e9quipe par courriel \u00e0 l\u2019adresse <strong><a href=\"mailto:food-donations@foodbankscanada.ca\">food-donations@foodbankscanada.ca<\/a>.<\/strong><\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-comment-mon-organisation-peut-elle-devenir-partenaire-de-banques-alimentaires-canada\">Comment mon organisation peut-elle devenir partenaire de Banques alimentaires Canada?<\/h4>\n\n\n\n<p>Il existe plusieurs fa\u00e7ons de collaborer avec Banques alimentaires Canada. Visitez notre\u00a0<a href=\"https:\/\/foodbankscanada.ca\/fr\/comment-aider\/partenariats-avec-des-entreprises\/\"><strong>page sur les partenariats avec les entreprises<\/strong><\/a>\u00a0pour en savoir plus, ou \u00e9crivez \u00e0 notre \u00e9quipe \u00e0\u00a0<strong><a href=\"mailto:partnerships@foodbankscanada.ca\">partnerships@foodbankscanada.ca<\/a>.<\/strong><\/p>\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 quoi sert mon don \u00e0 Banques alimentaires Canada? Votre soutien procure un soulagement essentiel aux banques alimentaires et aux familles en soulageant la faim aujourd\u2019hui et en pr\u00e9venant la faim demain. Voici comment votre don nous aide&nbsp;: Pour en savoir plus Comment puis-je obtenir une copie de mon re\u00e7u fiscal? Pour les dons en&#8230;<\/p>\n","protected":false},"author":36,"featured_media":49612,"parent":42631,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width-page.blade.php","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_opengraph-image":"","_yoast_wpseo_opengraph-image-id":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_twitter-image":"","_yoast_wpseo_twitter-image-id":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-49610","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Foire aux questions - Banques alimentaires Canada<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foire aux questions\" \/>\n<meta property=\"og:description\" content=\"\u00c0 quoi sert mon don \u00e0 Banques alimentaires Canada? Votre soutien procure un soulagement essentiel aux banques alimentaires et aux familles en soulageant la faim aujourd\u2019hui et en pr\u00e9venant la faim demain. Voici comment votre don nous aide&nbsp;: Pour en savoir plus Comment puis-je obtenir une copie de mon re\u00e7u fiscal? Pour les dons en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/\" \/>\n<meta property=\"og:site_name\" content=\"Banques alimentaires Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T15:30:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/\",\"url\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/\",\"name\":\"Foire aux questions - Banques alimentaires Canada\",\"isPartOf\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg\",\"datePublished\":\"2026-07-30T15:22:49+00:00\",\"dateModified\":\"2026-07-30T15:30:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage\",\"url\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg\",\"contentUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg\",\"width\":6000,\"height\":4000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/foodbankscanada.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ressources\",\"item\":\"https:\/\/foodbankscanada.ca\/fr\/ressources\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Foire aux questions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"name\":\"Banques alimentaires Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\",\"name\":\"Food Banks Canada\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"contentUrl\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"width\":377,\"height\":89,\"caption\":\"Food Banks Canada\"},\"image\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Foire aux questions - Banques alimentaires Canada","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Foire aux questions","og_description":"\u00c0 quoi sert mon don \u00e0 Banques alimentaires Canada? Votre soutien procure un soulagement essentiel aux banques alimentaires et aux familles en soulageant la faim aujourd\u2019hui et en pr\u00e9venant la faim demain. Voici comment votre don nous aide&nbsp;: Pour en savoir plus Comment puis-je obtenir une copie de mon re\u00e7u fiscal? Pour les dons en...","og_url":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/","og_site_name":"Banques alimentaires Canada","article_modified_time":"2026-07-30T15:30:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/","url":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/","name":"Foire aux questions - Banques alimentaires Canada","isPartOf":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage"},"image":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage"},"thumbnailUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg","datePublished":"2026-07-30T15:22:49+00:00","dateModified":"2026-07-30T15:30:15+00:00","breadcrumb":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#primaryimage","url":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg","contentUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/07\/iStock-1740859563.jpg","width":6000,"height":4000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/ressources\/foire-aux-questions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/foodbankscanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ressources","item":"https:\/\/foodbankscanada.ca\/fr\/ressources\/"},{"@type":"ListItem","position":3,"name":"Foire aux questions"}]},{"@type":"WebSite","@id":"https:\/\/foodbankscanada.ca\/fr\/#website","url":"https:\/\/foodbankscanada.ca\/fr\/","name":"Banques alimentaires Canada","description":"","publisher":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/foodbankscanada.ca\/fr\/#organization","name":"Food Banks Canada","url":"https:\/\/foodbankscanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","contentUrl":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","width":377,"height":89,"caption":"Food Banks Canada"},"image":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/49610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=49610"}],"version-history":[{"count":5,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/49610\/revisions"}],"predecessor-version":[{"id":49631,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/49610\/revisions\/49631"}],"up":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/42631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media\/49612"}],"wp:attachment":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=49610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=49610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=49610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}