{"id":8162,"date":"2022-03-17T10:23:06","date_gmt":"2022-03-17T14:23:06","guid":{"rendered":"https:\/\/prod2020.foodbankscanada.ca\/about-us\/conseil-dadministration\/"},"modified":"2026-07-02T13:54:39","modified_gmt":"2026-07-02T17:54:39","slug":"conseil-dadministration","status":"publish","type":"page","link":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/","title":{"rendered":"Conseil d\u2019administration"},"content":{"rendered":"\n<p>Notre conseil d&#8217;administration applique son expertise et son sens aigu des affaires pour nous aider \u00e0 trouver des solutions \u00e0 la faim au Canada. Le conseil guide notre orientation strat\u00e9gique, assure la responsabilit\u00e9 financi\u00e8re et nous aide \u00e0 assurer la transparence dans la pr\u00e9sentation de rapports au public.<\/p>\n\n\n\n<h2 class=\"wp-block-heading mt-4 mb-4\" id=\"h-gestion-des-banques-alimentaires-canada\">Gestion des Banques alimentaires Canada<\/h2>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Peter Singer<\/strong>, <strong><strong><strong><strong><strong><strong>pr\u00e9sident du conseil<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Pr\u00e9sident du CA | Thomas, Large &amp; Singer Inc.<\/p>\n\n\n\n<p>Peter Singer est pr\u00e9sident de&nbsp;<em>Thomas, Large and Singer Inc<\/em>., une entreprise familiale priv\u00e9e sp\u00e9cialis\u00e9e dans la distribution et le courtage alimentaire, fond\u00e9e en 1912. Peter joue un r\u00f4le actif dans l\u2019industrie alimentaire, ayant pr\u00e9sid\u00e9 les associations des courtiers alimentaires de l\u2019Ontario et du Canada, ainsi que l\u2019<em>Association of Sales and Marketing Companies<\/em>&nbsp;\u00e0 Washington D.C. et&nbsp;<em>GS1 Canada<\/em>. Il a occup\u00e9 des postes de direction au sein de conseils d\u2019administration d\u2019organismes \u0153uvrant dans les domaines de la sant\u00e9, de l\u2019environnement, des communaut\u00e9s et des institutions religieuses. Peter est fier d\u2019avoir re\u00e7u le prix&nbsp;<em>Golden Pencil<\/em>&nbsp;de l\u2019industrie alimentaire en 2008, ainsi que la d\u00e9signation de&nbsp;<em>membre \u00e0 vie<\/em>&nbsp;de la F\u00e9d\u00e9ration canadienne des \u00e9piciers ind\u00e9pendants en 2012.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-2.png\" alt=\"\" class=\"wp-image-46188\" style=\"aspect-ratio:1;object-fit:cover;width:250px\" srcset=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-2.png 350w, https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-2-300x300.png 300w, https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-2-150x150.png 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Ryan Bahadur<\/strong>, <strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>vice-<strong><strong><strong><strong><strong><strong>pr\u00e9sident du conseil<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Vice-pr\u00e9sident, finance | Keurig Canada Inc.<\/p>\n\n\n\n<p>Ryan joue un r\u00f4le cl\u00e9 au sein de l\u2019\u00e9quipe de direction canadienne de Keurig Dr Pepper. Il est responsable de la strat\u00e9gie, du d\u00e9veloppement de l\u2019entreprise et de la supervision de toutes les fonctions des finances et des technologies de l\u2019information. Ryan occupait auparavant les m\u00eames fonctions de chef de la direction financi\u00e8re chez Kellogg Canada, un r\u00f4le qu\u2019il a obtenu apr\u00e8s avoir grimp\u00e9 les \u00e9chelons au sein de la direction des finances de l\u2019entreprise. Ryan a suivi le programme de perfectionnement du leadership des cadres \u00e0 la Harvard Business School et est comptable professionnel agr\u00e9\u00e9 (CPA).<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Ilya-Bahar.jpg\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong>Ilya Bahar<\/strong><br><\/strong><\/strong><\/strong>Partenaire \u00e0 la retraite | PWC Canada<\/p>\n\n\n\n<p>Jusqu&#8217;\u00e0 sa retraite en 2018, Ilya a dirig\u00e9 le cabinet d\u2019expert-conseil de PwC pour les march\u00e9s de consommation au Canada, o\u00f9 il a dirig\u00e9 des initiatives strat\u00e9giques pour des clients de premier plan pour les produits de d\u00e9tail et de consommation. Avant de rejoindre PwC, Ilya a travaill\u00e9 pendant dix ans en tant qu&#8217;associ\u00e9 chez IBM, o\u00f9 il a occup\u00e9 divers postes de direction au Canada et au Br\u00e9sil. Il \u00e9tait \u00e9galement directeur g\u00e9n\u00e9ral de Premier Foods, division industrielle, une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans les produits nutritionnels pour le march\u00e9 de la restauration collective en Afrique du Sud. Ilya a si\u00e9g\u00e9 au conseil consultatif de Ryerson Retail Management School et a conseill\u00e9 les Produits alimentaires et de consommation du Canada (ACPC) et le Conseil canadien du commerce de d\u00e9tail (CCCD) dans le cadre de nombreuses initiatives de l&#8217;industrie.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"4938\" height=\"3579\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/2024-09-23-Head-Shots-6.jpg\" alt=\"\" class=\"wp-image-45911\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong>Vince Barletta<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong>President and CEO | Harvest Manitoba<\/p>\n\n\n\n<p>Vince est pr\u00e9sident et chef de la direction de Harvest Manitoba et a \u00e9t\u00e9 membre du plus r\u00e9cent groupe de r\u00e9flexion de Banques alimentaires Canada, contribuant \u00e0 l\u2019\u00e9laboration du nouveau plan strat\u00e9gique de l\u2019organisme. Il poss\u00e8de une connaissance approfondie de l\u2019ins\u00e9curit\u00e9 alimentaire et des banques alimentaires au Manitoba. Il a consacr\u00e9 beaucoup d\u2019efforts \u00e0 travailler avec les communaut\u00e9s autochtones du Manitoba pour trouver des solutions \u00e0 l\u2019ins\u00e9curit\u00e9 alimentaire au sein de ces communaut\u00e9s.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Linda-Beairsto.jpg\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Linda Beairsto<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Associ\u00e9e, McCarthy T\u00e9trault et pr\u00e9sidente, MT&gt;R\u00e9seau<\/p>\n\n\n\n<p>Linda poss\u00e8de plus de 30 ans d\u2019exp\u00e9rience dans les domaines juridique et commercial. En plus d\u2019\u00eatre associ\u00e9e chez McCarthy T\u00e9trault, elle pr\u00e9side et dirige la division novatrice MT&gt;R\u00e9seau, une propri\u00e9t\u00e9 exclusive du cabinet, qui compte plus de 100 avocats contractuels ind\u00e9pendants de haut calibre partout au Canada. Avant de se joindre \u00e0 McCarthy, Linda \u00e9tait membre de la haute direction d\u2019Algonquin Power &amp; Utilities Corp, o\u00f9 elle a occup\u00e9 les postes d\u2019avocate g\u00e9n\u00e9rale, de secr\u00e9taire g\u00e9n\u00e9rale et de chef de la conformit\u00e9. Au cours de sa carri\u00e8re, Linda a occup\u00e9 des postes de haute direction et de direction juridique au sein de divers secteurs (\u00e9lectricit\u00e9, services publics, industrie pharmaceutique, sant\u00e9, pi\u00e8ces automobiles, fabrication, emballage, alimentation, produits chimiques, immobilier commercial et services financiers). Linda d\u00e9tient le titre de directrice agr\u00e9\u00e9e (Chartered Director) du Directors College de l\u2019Universit\u00e9 McMaster. Elle a \u00e9galement obtenu une certification en conformit\u00e9 et en \u00e9thique d\u00e9livr\u00e9e par le Compliance Certification Board. De plus, elle s\u2019est vue confier divers r\u00f4les de direction au sein de conseils d\u2019administration dans des secteurs \u00e0 but lucratif et sans but lucratif. Linda d\u00e9tient un baccalaur\u00e9at en droit de l\u2019Universit\u00e9 du Nouveau-Brunswick et un baccalaur\u00e9at en \u00e9tudes asiatiques de l\u2019Universit\u00e9 de la Colombie-Britannique. En 2017, elle a \u00e9t\u00e9 finaliste pour les prix de recrutement du National Post et ZSA dans deux cat\u00e9gories : avocate g\u00e9n\u00e9rale canadienne de l\u2019ann\u00e9e en 2017 et meilleure entente de l\u2019ann\u00e9e en 2017.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Marjorie-Bencz.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Marjorie Bencz<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Directrice g\u00e9n\u00e9rale | Banque alimentaire d\u2019Edmonton<\/p>\n\n\n\n<p>Marjorie Bencz a commenc\u00e9 sa carri\u00e8re \u00e0 la banque alimentaire d\u2019Edmonton en 1987 \u00e0 titre de b\u00e9n\u00e9vole et elle en assure la direction depuis 1989. Au fil des ans, le travail et le d\u00e9vouement de Marjorie lui ont valu plusieurs prix communautaires, dont un dipl\u00f4me honorifique en sant\u00e9 et \u00e9tudes communautaires du coll\u00e8ge Grand MacEwan et le titre de Woman of Vision (femme d\u2019influence) de Global News. Son \u0153uvre continue aupr\u00e8s des Canadiens a \u00e9galement \u00e9t\u00e9 reconnue \u00e0 l\u2019\u00e9chelle nationale lorsqu\u2019elle a \u00e9t\u00e9 nomm\u00e9e au sein de l\u2019Ordre du Canada dans la cat\u00e9gorie des sciences sociales, en 2006. Marjorie a re\u00e7u en mai 2012 le prix Femmes de m\u00e9rite du YMCA dans la cat\u00e9gorie du service communautaire. Toujours en 2012, elle a re\u00e7u la M\u00e9daille du jubil\u00e9 de diamant de la reine. En juin 2015, Marjorie a \u00e9t\u00e9 intronis\u00e9e au Temple de la renomm\u00e9e de la Ville d\u2019Edmonton. Marjorie croit que cette reconnaissance n\u2019est pas pour son travail; elle l\u2019attribue plut\u00f4t au soutien que lui apportent ses concitoyens d\u2019Edmonton, de l\u2019Alberta et du Canada pour r\u00e9duire la faim dans nos communaut\u00e9s.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Tony-Chow.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Tony Chow<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Pr\u00e9sident | Compagnie d\u2019embouteillage Coke Canada<\/p>\n\n\n\n<p>Tony Chow est le pr\u00e9sident de la Compagnie d\u2019embouteillage Coke Canada. Il est un leader respect\u00e9 et chevronn\u00e9 de l\u2019industrie des aliments et des boissons, comptant plus de 25 ans d\u2019exp\u00e9rience dans les produits de consommation emball\u00e9s. Il poss\u00e8de une vaste exp\u00e9rience en direction d\u2019entreprises dans le cadre de leur transformation et de leur croissance. Avant de se joindre \u00e0 Coke Canada, il a \u00e9t\u00e9 pr\u00e9sident de Kellanova Canada et membre de l\u2019\u00e9quipe de direction nord-am\u00e9ricaine de Kellanova. Dans ces fonctions, il a jou\u00e9 un r\u00f4le cl\u00e9 dans la transformation r\u00e9ussie de Kellogg Canada en deux nouvelles entreprises, et a dirig\u00e9 la mise en place de la nouvelle vision, culture et orientation strat\u00e9gique de Kellanova Canada. De 2017 \u00e0 2019, il a dirig\u00e9 Kashi aux \u00c9tats-Unis, p\u00e9riode au cours de laquelle il a r\u00e9ussi \u00e0 redresser l\u2019entreprise. Il avait auparavant occup\u00e9 plusieurs postes successifs dans les domaines des ventes, du marketing et de la gestion au Canada et aux \u00c9tats-Unis. Il est tr\u00e8s important pour lui de redonner \u00e0 la communaut\u00e9. L\u2019\u00e9radication de la faim est une cause qui lui tient particuli\u00e8rement \u00e0 c\u0153ur. En plus d\u2019\u00eatre membre du conseil d\u2019administration de Banques alimentaires Canada, il dirige les efforts communautaires de l\u2019embouteilleur local de Coke Canada, y compris les partenariats communautaires et les initiatives de b\u00e9n\u00e9volat des employ\u00e9s.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/06\/Barb-1A-1024x960.jpg\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Barbara Gosse<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Associ\u00e9e directrice, Services \u00e0 but non lucratif | The Osborne Group<\/p>\n\n\n\n<p>\u00c0 titre d\u2019associ\u00e9e directrice, Services \u00e0 but non lucratif au sein d\u2019Osborne, Barbara&nbsp;Gosse conseille les organismes de bienfaisance et les organismes \u00e0 but non lucratif sur les syst\u00e8mes de gouvernance et de gestion internes, la planification strat\u00e9gique et op\u00e9rationnelle et l\u2019efficacit\u00e9 organisationnelle. Elle offre \u00e9galement un soutien en mati\u00e8re de leadership ex\u00e9cutif \u00e0 temps partiel ou int\u00e9rimaire et collabore \u00e9troitement avec les conseils d\u2019administration, les \u00e9quipes de direction et le personnel afin de b\u00e2tir des fondations organisationnelles solides, transparentes et responsables. Auparavant, elle occupait le poste de chef de la direction du Centre to End Human Trafficking, dont elle est aussi la fondatrice. \u00c0 ce titre, elle a assur\u00e9 un leadership national et dirig\u00e9 la conception, le d\u00e9veloppement et le lancement de la Ligne d\u2019urgence canadienne contre la traite des personnes. Elle a auparavant occup\u00e9 des postes de direction au sein de la Fondation canadienne des femmes et de Prosp\u00e9rit\u00e9 Canada. Elle a pr\u00e9sent\u00e9 des \u00e9l\u00e9ments de preuve aux comit\u00e9s l\u00e9gislatifs des gouvernements provinciaux et f\u00e9d\u00e9ral, et a particip\u00e9 \u00e0 des consultations nationales et internationales abordant les enjeux de la pauvret\u00e9, de l\u2019itin\u00e9rance, des droits des personnes handicap\u00e9es, de la violence fond\u00e9e sur le genre et de la traite de personnes. Elle est b\u00e9n\u00e9vole depuis de nombreuses ann\u00e9es aupr\u00e8s de l\u2019organisme Out of the Cold de Toronto et suit actuellement le programme de ma\u00eetre-jardinier. Elle est laur\u00e9ate du Prix du premier ministre de l\u2019Ontario \u00e0 l\u2019intention des femmes pour l\u2019excellence en d\u00e9veloppement communautaire&nbsp;2018.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Dany-Hetu.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong>Dany H\u00e9tu<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Directeur g\u00e9n\u00e9ral | Moisson Rive-Sud<\/p>\n\n\n\n<p>Dany H\u00e9tu a servi dans les Forces arm\u00e9es canadiennes comme officier d\u2019infanterie. Il a occup\u00e9 tous les \u00e9chelons strat\u00e9giques, op\u00e9rationnels et tactiques au pays et \u00e0 l\u2019\u00e9tranger, et il a particip\u00e9 \u00e0 plusieurs missions, notamment en Afghanistan. Il s\u2019est joint \u00e0 Moisson Rive-Sud apr\u00e8s plus de 32 ann\u00e9es de service. Au cours de sa carri\u00e8re, M. H\u00e9tu a travaill\u00e9 \u00e0 titre d\u2019administrateur de la Caisse Desjardins des militaires. Titulaire d\u2019un baccalaur\u00e9at avec sp\u00e9cialisation en sciences politiques de l\u2019Universit\u00e9 d\u2019Ottawa, il est administrateur de soci\u00e9t\u00e9s certifi\u00e9 (ASC) et a suivi le programme de certification universitaire en gouvernance des soci\u00e9t\u00e9s du Coll\u00e8ge des administrateurs de soci\u00e9t\u00e9s de l\u2019Universit\u00e9 Laval.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Mary-Jo-Hewat.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong>Mary-Jo Hewat<\/strong><br><\/strong><\/strong><\/strong><\/strong>Premi\u00e8re vice-pr\u00e9sidente, Ressources humaines et installations | Genworth Canada<\/p>\n\n\n\n<p>M<sup>me<\/sup>&nbsp;Hewat poss\u00e8de plus de 25 ann\u00e9es d\u2019exp\u00e9rience en ressources humaines et occupe actuellement le poste de premi\u00e8re vice-pr\u00e9sidente, Ressources humaines et installations \u00e0 Genworth Canada. Avant de se joindre \u00e0 Genworth Canada, elle assumait les fonctions de premi\u00e8re vice-pr\u00e9sidente, Partenariats commerciaux des RH au R\u00e9gime de retraite des employ\u00e9s municipaux de l\u2019Ontario (OMERS). Elle est titulaire du titre de directrice agr\u00e9\u00e9e (C.Dir.) et de cadre principale en ressources humaines agr\u00e9\u00e9e (C.P.R.H.A.). En plus d\u2019\u00eatre membre du conseil d\u2019administration de Banques alimentaires Canada, elle si\u00e8ge au conseil consultatif des programmes de Gestion des ressources humaines et de Conception organisationnelle de l\u2019Universit\u00e9 Ryerson.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-1.png\" alt=\"\" class=\"wp-image-46185\" style=\"aspect-ratio:1;object-fit:cover;width:250px\" srcset=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-1.png 350w, https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-1-300x300.png 300w, https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/10\/FBC_Board-1-150x150.png 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong>Simon Laroche<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Pr\u00e9sident | Kraft Heinz Canada<\/p>\n\n\n\n<p>Simon Laroche est le pr\u00e9sident de Kraft Heinz Canada, l\u2019un des principaux producteurs de caf\u00e9 en Am\u00e9rique du Nord et le plus important fabricant multinational d\u2019aliments au Canada. Ayant v\u00e9cu et travaill\u00e9 sur trois continents, Simon poss\u00e8de une vaste expertise interfonctionnelle dans la cr\u00e9ation de cultures qui favorisent l\u2019engagement du personnel et dans l\u2019am\u00e9lioration des r\u00e9sultats d\u2019affaires. Avant d\u2019occuper son poste actuel, Simon \u00e9tait \u00e0 la t\u00eate d\u2019une \u00e9quipe de 2 500 personnes en tant que pr\u00e9sident de Kraft Heinz Australie, Nouvelle-Z\u00e9lande et Asie du Nord-Est. Il a dirig\u00e9 le redressement de l\u2019entreprise, am\u00e9liorant consid\u00e9rablement la rentabilit\u00e9 et la croissance ainsi que la mobilisation globale des employ\u00e9s. Avant de se joindre \u00e0 Kraft Heinz, Simon a travaill\u00e9 pendant 14 ans pour les Brasseries Labatt du Canada, o\u00f9 il a occup\u00e9 plusieurs postes de haute direction, dont celui de vice-pr\u00e9sident des ventes pour le march\u00e9 canadien. P\u00e8re de deux jeunes filles, Simon est titulaire d\u2019un baccalaur\u00e9at en finances de HEC Montr\u00e9al et il si\u00e8ge au conseil d\u2019administration de Produits alimentaires, de sant\u00e9 et de consommation du Canada.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"525\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2025\/06\/The-Honourable-Percy-P-Mockler.jpg\" alt=\"\" class=\"wp-image-44021\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong>L\u2019honorable Percy Mockler<\/strong><\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>S\u00e9nateur canadien \u00e0 la retraite repr\u00e9sentant | Province du Nouveau-Brunswick<\/p>\n\n\n\n<p>L&#8217;honorable Percy Mockler a \u00e9t\u00e9 s\u00e9nateur pendant 15 ans, repr\u00e9sentant la province du Nouveau-Brunswick. Il a pr\u00e9sid\u00e9 le Comit\u00e9 des finances nationales et le Comit\u00e9 de l&#8217;agriculture et des for\u00eats. Il a \u00e9t\u00e9 membre de nombreux autres comit\u00e9s s\u00e9natoriaux : banques, \u00e9nergie, environnement et ressources naturelles, et langues officielles. Il a dirig\u00e9 l&#8217;\u00e9tude s\u00e9natoriale sur la sant\u00e9 des abeilles et l&#8217;alimentation durable.<\/p>\n\n\n\n<p>Il a effectu\u00e9 six mandats comme d\u00e9put\u00e9 \u00e0 l&#8217;Assembl\u00e9e l\u00e9gislative du Nouveau-Brunswick et a \u00e9t\u00e9 ministre de plusieurs minist\u00e8res, dont celui des Services familiaux et communautaires, celui des Affaires intergouvernementales et celui du Solliciteur g\u00e9n\u00e9ral. Au total, Percy Mockler a consacr\u00e9 plus de 42 ans \u00e0 la fonction publique canadienne.<\/p>\n\n\n\n<p>Percy Mockler est titulaire d&#8217;un MBA et d&#8217;un doctorat honorifique en sciences politiques de l&#8217;Universit\u00e9 de Moncton.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized image-block is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/June-Muir-62328f9c80fe2.png\" alt=\"\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>June Muir<\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>Chef de la direction | UHC \u2013 Hub of Opportunities<\/p>\n\n\n\n<p>June Muir \u0153uvre dans le secteur du d\u00e9pannage alimentaire et de la bienfaisance depuis 2000, ann\u00e9e o\u00f9 elle a entrepris un changement de carri\u00e8re et s\u2019est jointe \u00e0 l\u2019\u00e9quipe de l\u2019UHC \u2013 Hub of Opportunities. \u00c0 titre de chef de la direction, elle dirige une \u00e9quipe interdisciplinaire tr\u00e8s efficace qui veille \u00e0 ce que la communaut\u00e9 de Windsor-Essex soit sensibilis\u00e9e aux besoins continus des personnes et des familles \u00e0 faible revenu. Passionn\u00e9e et d\u00e9vou\u00e9e, June d\u00e9fend haut et fort les plus d\u00e9munis et am\u00e9liore la qualit\u00e9 de vie des personnes aux prises avec le ch\u00f4mage et des difficult\u00e9s financi\u00e8res. June est toujours pr\u00eate \u00e0 \u00e9tablir des partenariats avec les fournisseurs de services communautaires de Windsor pour assurer un avenir plus radieux et stable aux clients de l\u2019UHC.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"509\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/DougMImage.jpg\" alt=\"\" class=\"wp-image-49055\" style=\"aspect-ratio:1;object-fit:cover;width:250px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong>Douglas Muzyka<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><br>Retired Chief Science and Technology Officer | &nbsp;DuPont &nbsp;<\/p>\n\n\n\n<p>Douglas est un chef d\u2019entreprise et un pr\u00e9sident de conseil d\u2019administration qui compte plus de 40&nbsp;ans d\u2019exp\u00e9rience dans les domaines des sciences, de la technologie, de la fabrication et de l\u2019innovation. Avant sa carri\u00e8re d\u2019administrateur d\u2019entreprise, Doug a pass\u00e9 trois d\u00e9cennies chez DuPont, o\u00f9 il a occup\u00e9 des postes de haute direction \u00e0 l\u2019\u00e9chelle internationale, avant d\u2019y obtenir le r\u00f4le de chef de la direction, Sciences et Technologies. Il si\u00e8ge actuellement \u00e0 titre de pr\u00e9sident du conseil d\u2019administration du Conseil national de recherches du Canada et de pr\u00e9sident du conseil du Centre de production de produits biologiques, et est \u00e9galement pr\u00e9sident de Chemtrade Logistics Income Fund, et membre du conseil d\u2019administration de Stella-Jones. Douglas est d\u00e9termin\u00e9 \u00e0 faire progresser la r\u00e9silience \u00e9conomique, la s\u00e9curit\u00e9 sanitaire et la capacit\u00e9 d\u2019innovation du Canada, et estime que l\u2019acc\u00e8s \u00e0 des aliments nutritifs est essentiel \u00e0 la sant\u00e9, \u00e0 la dignit\u00e9 et aux possibilit\u00e9s.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content-border-bottom is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column d-flex justify-content-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized image-block is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/JohnP.png\" alt=\"\" class=\"wp-image-49057\" style=\"aspect-ratio:1;object-fit:cover;width:250px\" srcset=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/JohnP.png 1080w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/JohnP-240x300.png 240w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/JohnP-819x1024.png 819w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/06\/JohnP-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong><strong><strong><strong><strong><strong><strong>John Peellegoda<\/strong><\/strong><br><\/strong><\/strong><\/strong><\/strong><\/strong>Chief Financial Officer and Senior Vice President of Strategy | Toronto Port Authority<\/p>\n\n\n\n<p>John est actuellement directeur financier et vice-pr\u00e9sident principal, Strat\u00e9gie, \u00e0 l\u2019Administration portuaire de Toronto, o\u00f9 il assure le leadership des fonctions li\u00e9es aux finances, \u00e0 la strat\u00e9gie, au d\u00e9veloppement commercial et \u00e0 la planification \u00e0 long terme. Avant d\u2019occuper son poste actuel, John a occup\u00e9 des postes de haute direction \u00e0 l\u2019Autorit\u00e9 a\u00e9roportuaire du Grand Toronto et \u00e0 Algonquin Power &amp; Utilities Corp. et a commenc\u00e9 sa carri\u00e8re chez PwC Canada. Fort de plus de deux d\u00e9cennies d\u2019exp\u00e9rience en finances d\u2019entreprise, en infrastructures, en gestion des risques et en planification op\u00e9rationnelle strat\u00e9gique, John apporte une expertise financi\u00e8re approfondie, une perspective strat\u00e9gique et un engagement \u00e0 l\u2019\u00e9gard d\u2019une gouvernance solide et de l\u2019impact communautaire.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group mt-3 mb-4 is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\" block block-button-with-modal button-with-modal  alignfull\" style=\"\">\n  \n  <!-- Button trigger modal -->\n  <button type=\"button\" class=\"btn-primary\" data-bs-toggle=\"modal\" data-bs-target=\"#exampleModal\">\n    Divulgation\n  <\/button>\n  \n  <!-- Modal -->\n  <div class=\"modal fade\" id=\"exampleModal\" tabindex=\"-1\" aria-labelledby=\"exampleModalLabel\" aria-hidden=\"true\">\n    <div class=\"modal-dialog modal-lg modal-dialog-centered\">\n      <div class=\"modal-content\">\n        <div class=\"modal-header\">\n          <h1 class=\"modal-title fs-5\" id=\"exampleModalLabel\">DIVILGATION<\/h1>\n          <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\n        <\/div>\n        <div class=\"modal-body\">\n          <p>Banques alimentaires Canada souhaite divulguer l\u2019objet et le montant de tout paiement de produits ou de services aux membres du conseil d\u2019administration ou aux entreprises dont un membre du conseil d\u2019administration est propri\u00e9taire, associ\u00e9 ou cadre sup\u00e9rieur.<\/p>\n<table class=\"table\">\n<thead class=\"table-dark\">\n<tr>\n<th scope=\"col\">Membre concern\u00e9<\/th>\n<th scope=\"col\">Objet<\/th>\n<th scope=\"col\">Montant<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td class=\"text-break\">Peter Singer \u2013 Chairman Thomas, Large &amp; Singer Inc.<\/td>\n<td class=\"text-break\">Paiement \u00e0 Emblem Logistics, une filiale de Thomas, Large &amp; Singer pour les services de co-emballage et de transport<\/td>\n<td class=\"text-break\">\n<div>F22 &#8211; $143,167<\/div>\n<div>F23 &#8211; $210,920<br \/>\nF24 &#8211; $145,453<br \/>\nF25 &#8211; $349,228<br \/>\nF26 &#8211; $147,978.03<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Notre conseil d&#8217;administration applique son expertise et son sens aigu des affaires pour nous aider \u00e0 trouver des solutions \u00e0 la faim au Canada. Le conseil guide notre orientation strat\u00e9gique, assure la responsabilit\u00e9 financi\u00e8re et nous aide \u00e0 assurer la transparence dans la pr\u00e9sentation de rapports au public. Gestion des Banques alimentaires Canada Peter Singer,&#8230;<\/p>\n","protected":false},"author":33,"featured_media":8030,"parent":5227,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_opengraph-image":"","_yoast_wpseo_opengraph-image-id":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_twitter-image":"","_yoast_wpseo_twitter-image-id":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-8162","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conseil d\u2019administration - Banques alimentaires Canada<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseil d\u2019administration\" \/>\n<meta property=\"og:description\" content=\"Notre conseil d&#8217;administration applique son expertise et son sens aigu des affaires pour nous aider \u00e0 trouver des solutions \u00e0 la faim au Canada. Le conseil guide notre orientation strat\u00e9gique, assure la responsabilit\u00e9 financi\u00e8re et nous aide \u00e0 assurer la transparence dans la pr\u00e9sentation de rapports au public. Gestion des Banques alimentaires Canada Peter Singer,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/\" \/>\n<meta property=\"og:site_name\" content=\"Banques alimentaires Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T17:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/\",\"url\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/\",\"name\":\"Conseil d\u2019administration - Banques alimentaires Canada\",\"isPartOf\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png\",\"datePublished\":\"2022-03-17T14:23:06+00:00\",\"dateModified\":\"2026-07-02T17:54:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage\",\"url\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png\",\"contentUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/foodbankscanada.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui sommes-nous\",\"item\":\"https:\/\/foodbankscanada.ca\/fr\/qui-sommes-nous\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseil d\u2019administration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"name\":\"Banques alimentaires Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\",\"name\":\"Food Banks Canada\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"contentUrl\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"width\":377,\"height\":89,\"caption\":\"Food Banks Canada\"},\"image\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conseil d\u2019administration - Banques alimentaires Canada","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Conseil d\u2019administration","og_description":"Notre conseil d&#8217;administration applique son expertise et son sens aigu des affaires pour nous aider \u00e0 trouver des solutions \u00e0 la faim au Canada. Le conseil guide notre orientation strat\u00e9gique, assure la responsabilit\u00e9 financi\u00e8re et nous aide \u00e0 assurer la transparence dans la pr\u00e9sentation de rapports au public. Gestion des Banques alimentaires Canada Peter Singer,...","og_url":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/","og_site_name":"Banques alimentaires Canada","article_modified_time":"2026-07-02T17:54:39+00:00","og_image":[{"url":"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/","url":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/","name":"Conseil d\u2019administration - Banques alimentaires Canada","isPartOf":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage"},"image":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage"},"thumbnailUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png","datePublished":"2022-03-17T14:23:06+00:00","dateModified":"2026-07-02T17:54:39+00:00","breadcrumb":{"@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#primaryimage","url":"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png","contentUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2022\/03\/Peter-Singer.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.foodbankscanada.ca\/fr\/qui-sommes-nous\/conseil-dadministration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/foodbankscanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Qui sommes-nous","item":"https:\/\/foodbankscanada.ca\/fr\/qui-sommes-nous\/"},{"@type":"ListItem","position":3,"name":"Conseil d\u2019administration"}]},{"@type":"WebSite","@id":"https:\/\/foodbankscanada.ca\/fr\/#website","url":"https:\/\/foodbankscanada.ca\/fr\/","name":"Banques alimentaires Canada","description":"","publisher":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/foodbankscanada.ca\/fr\/#organization","name":"Food Banks Canada","url":"https:\/\/foodbankscanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","contentUrl":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","width":377,"height":89,"caption":"Food Banks Canada"},"image":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/8162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=8162"}],"version-history":[{"count":119,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/8162\/revisions"}],"predecessor-version":[{"id":49284,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/8162\/revisions\/49284"}],"up":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/pages\/5227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media\/8030"}],"wp:attachment":[{"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=8162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=8162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=8162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}